{"id":56,"count":12,"description":"","link":"https:\/\/accesorioskh.com\/index.php\/product-category\/oro-laminado\/aretes-oro-laminado\/","name":"Aretes","slug":"aretes-oro-laminado","taxonomy":"product_cat","parent":52,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aretes Archivos - KH ACCESORIOS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesorioskh.com\/index.php\/product-category\/oro-laminado\/aretes-oro-laminado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aretes Archivos - KH ACCESORIOS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesorioskh.com\/index.php\/product-category\/oro-laminado\/aretes-oro-laminado\/\" \/>\n<meta property=\"og:site_name\" content=\"KH ACCESORIOS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/accesorioskh.com\\\/index.php\\\/product-category\\\/oro-laminado\\\/aretes-oro-laminado\\\/\",\"url\":\"https:\\\/\\\/accesorioskh.com\\\/index.php\\\/product-category\\\/oro-laminado\\\/aretes-oro-laminado\\\/\",\"name\":\"Aretes Archivos - KH ACCESORIOS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesorioskh.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesorioskh.com\\\/index.php\\\/product-category\\\/oro-laminado\\\/aretes-oro-laminado\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesorioskh.com\\\/index.php\\\/product-category\\\/oro-laminado\\\/aretes-oro-laminado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/accesorioskh.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oro laminado\",\"item\":\"https:\\\/\\\/accesorioskh.com\\\/index.php\\\/product-category\\\/oro-laminado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aretes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesorioskh.com\\\/#website\",\"url\":\"https:\\\/\\\/accesorioskh.com\\\/\",\"name\":\"Accesorios KH\",\"description\":\"Accesorios para mujer y hombre\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesorioskh.com\\\/#organization\"},\"alternateName\":\"KH accesorios\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesorioskh.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesorioskh.com\\\/#organization\",\"name\":\"Accesorios KH\",\"alternateName\":\"KH accesorios\",\"url\":\"https:\\\/\\\/accesorioskh.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/accesorioskh.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesorioskh.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-logo-2.png\",\"contentUrl\":\"https:\\\/\\\/accesorioskh.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-logo-2.png\",\"width\":537,\"height\":496,\"caption\":\"Accesorios KH\"},\"image\":{\"@id\":\"https:\\\/\\\/accesorioskh.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aretes Archivos - KH ACCESORIOS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesorioskh.com\/index.php\/product-category\/oro-laminado\/aretes-oro-laminado\/","og_locale":"es_ES","og_type":"article","og_title":"Aretes Archivos - KH ACCESORIOS","og_url":"https:\/\/accesorioskh.com\/index.php\/product-category\/oro-laminado\/aretes-oro-laminado\/","og_site_name":"KH ACCESORIOS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/accesorioskh.com\/index.php\/product-category\/oro-laminado\/aretes-oro-laminado\/","url":"https:\/\/accesorioskh.com\/index.php\/product-category\/oro-laminado\/aretes-oro-laminado\/","name":"Aretes Archivos - KH ACCESORIOS","isPartOf":{"@id":"https:\/\/accesorioskh.com\/#website"},"breadcrumb":{"@id":"https:\/\/accesorioskh.com\/index.php\/product-category\/oro-laminado\/aretes-oro-laminado\/#breadcrumb"},"inLanguage":"es-CO"},{"@type":"BreadcrumbList","@id":"https:\/\/accesorioskh.com\/index.php\/product-category\/oro-laminado\/aretes-oro-laminado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/accesorioskh.com\/"},{"@type":"ListItem","position":2,"name":"Oro laminado","item":"https:\/\/accesorioskh.com\/index.php\/product-category\/oro-laminado\/"},{"@type":"ListItem","position":3,"name":"Aretes"}]},{"@type":"WebSite","@id":"https:\/\/accesorioskh.com\/#website","url":"https:\/\/accesorioskh.com\/","name":"Accesorios KH","description":"Accesorios para mujer y hombre","publisher":{"@id":"https:\/\/accesorioskh.com\/#organization"},"alternateName":"KH accesorios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesorioskh.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/accesorioskh.com\/#organization","name":"Accesorios KH","alternateName":"KH accesorios","url":"https:\/\/accesorioskh.com\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/accesorioskh.com\/#\/schema\/logo\/image\/","url":"https:\/\/accesorioskh.com\/wp-content\/uploads\/2024\/02\/cropped-logo-2.png","contentUrl":"https:\/\/accesorioskh.com\/wp-content\/uploads\/2024\/02\/cropped-logo-2.png","width":537,"height":496,"caption":"Accesorios KH"},"image":{"@id":"https:\/\/accesorioskh.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/accesorioskh.com\/index.php\/wp-json\/wp\/v2\/product_cat\/56","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesorioskh.com\/index.php\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/accesorioskh.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/accesorioskh.com\/index.php\/wp-json\/wp\/v2\/product_cat\/52"}],"wp:post_type":[{"href":"https:\/\/accesorioskh.com\/index.php\/wp-json\/wp\/v2\/product?product_cat=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}